{"id":5481,"date":"2014-01-14T14:45:37","date_gmt":"2014-01-14T19:45:37","guid":{"rendered":"http:\/\/westbendnews.net\/autonews\/?p=5481"},"modified":"2014-01-14T14:45:37","modified_gmt":"2014-01-14T19:45:37","slug":"divine-mercy-spelling-bee-winners","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/","title":{"rendered":"Divine Mercy Spelling Bee Winners"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/westbendnews.net\/autonews\/wp-content\/uploads\/2014\/01\/Divine-Mercy-Sp-Bee.jpeg\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-5482\" alt=\"Divine Mercy Sp Bee\" src=\"https:\/\/i0.wp.com\/westbendnews.net\/autonews\/wp-content\/uploads\/2014\/01\/Divine-Mercy-Sp-Bee.jpeg?resize=666%2C428\" width=\"666\" height=\"428\" \/><\/a>Divine Mercy Catholic School recently held their annual spelling bee. Kaden Sutton, Grade 5, son of Kylie Folsum and Mitch Sutton won the spelling bee by spelling the word obsidian correctly. Kenadie Daeger, Grade 5, daughter of Jeremy &amp; Michele Daeger came in second place.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Divine Mercy Catholic School recently held their annual spelling bee. Kaden Sutton, Grade 5, son of Kylie Folsum and Mitch<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6,7],"tags":[285,107,108,283],"class_list":["post-5481","post","type-post","status-publish","format-standard","hentry","category-community","category-school","tag-bee","tag-divine","tag-mercy","tag-spelling"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Divine Mercy Spelling Bee Winners | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-01-14T19:45:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-01-14T19:45:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Divine Mercy Spelling Bee Winners | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&amp;ssl=1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#article\",\"name\":\"Divine Mercy Spelling Bee Winners | West Bend News\",\"headline\":\"Divine Mercy Spelling Bee Winners\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/Divine-Mercy-Sp-Bee.jpeg\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#articleImage\"},\"datePublished\":\"2014-01-14T14:45:37-05:00\",\"dateModified\":\"2014-01-14T14:45:37-05:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#webpage\"},\"articleSection\":\"Community, School, Bee, Divine, Mercy, Spelling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/#listItem\",\"name\":\"Community\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/#listItem\",\"position\":2,\"name\":\"Community\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#listItem\",\"name\":\"Divine Mercy Spelling Bee Winners\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#listItem\",\"position\":3,\"name\":\"Divine Mercy Spelling Bee Winners\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/#listItem\",\"name\":\"Community\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/\",\"name\":\"Divine Mercy Spelling Bee Winners | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/divine-mercy-spelling-bee-winners\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"datePublished\":\"2014-01-14T14:45:37-05:00\",\"dateModified\":\"2014-01-14T14:45:37-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Divine Mercy Spelling Bee Winners | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#article","name":"Divine Mercy Spelling Bee Winners | West Bend News","headline":"Divine Mercy Spelling Bee Winners","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/westbendnews.net\/autonews\/wp-content\/uploads\/2014\/01\/Divine-Mercy-Sp-Bee.jpeg","@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#articleImage"},"datePublished":"2014-01-14T14:45:37-05:00","dateModified":"2014-01-14T14:45:37-05:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#webpage"},"articleSection":"Community, School, Bee, Divine, Mercy, Spelling"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/#listItem","name":"Community"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/#listItem","position":2,"name":"Community","item":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#listItem","name":"Divine Mercy Spelling Bee Winners"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#listItem","position":3,"name":"Divine Mercy Spelling Bee Winners","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/#listItem","name":"Community"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/","name":"Divine Mercy Spelling Bee Winners | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"datePublished":"2014-01-14T14:45:37-05:00","dateModified":"2014-01-14T14:45:37-05:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"Divine Mercy Spelling Bee Winners | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/divine-mercy-spelling-bee-winners\/","og:image":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1","og:image:secure_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1","article:published_time":"2014-01-14T19:45:37+00:00","article:modified_time":"2014-01-14T19:45:37+00:00","twitter:card":"summary","twitter:title":"Divine Mercy Spelling Bee Winners | West Bend News","twitter:image":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&ssl=1"},"aioseo_meta_data":{"post_id":"5481","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-06 19:34:41","updated":"2025-06-04 18:30:22","seo_analyzer_scan_date":null},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-1qp","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-21 21:39:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/5481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=5481"}],"version-history":[{"count":0,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/5481\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=5481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=5481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=5481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}