{"id":41602,"date":"2023-09-25T13:25:38","date_gmt":"2023-09-25T17:25:38","guid":{"rendered":"https:\/\/www.westbendnews.net\/autonews\/?p=41602"},"modified":"2023-09-25T13:25:40","modified_gmt":"2023-09-25T17:25:40","slug":"arlette-ann-lopshire","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/","title":{"rendered":"Arlette Ann Lopshire"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg?w=225&#038;ssl=1\" alt=\"\" class=\"wp-image-41603\" style=\"width:225px\"  srcset=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg?w=318&amp;ssl=1 318w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg?resize=260%2C374&amp;ssl=1 260w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg?resize=160%2C230&amp;ssl=1 160w\" sizes=\"auto, (max-width: 318px) 100vw, 318px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">PAYNE, OH:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arlette Ann Lopshire, 90, of Payne, passed away Saturday, September 23, 2023, at Vancrest of Payne.<br>Arlette was born in Hicksville on July 13, 1933, a daughter of the late La Moile (Miller) &amp; Ernest Levi Burley.<br>On June 1, 1950, Arlette married the love of her life, Orlando James Lopshire. Arlette worked at Wayne Trace schools, cooking and cleaning for many years. She was a member of Divine Mercy Catholic Church. Guided by her faith, Arlette created a loving home for her children and grandchildren, and cherished the time she spent with them.\u00a0<br>She will be sadly missed by her children; Jimmy (Sylvia), Ernest (Donita), &amp; David (Sue) Lopshire; sister, Linda Garman; 6 grandchildren; &amp; 12 great grandchildren.\u00a0<br>She was preceded in death by her husband, Orlando, on October 21, 2007, &amp; her siblings, Fred Burley, Monyea Countryman, Karen Stephenson, &amp; Jerry Burley.\u00a0<br>Viewing will be Tuesday, September 26, 2023, from 4-6 PM with a 6 PM Rosary at Dooley Funeral Home, 5761 SR 500, Payne, Ohio 45880.<br>Viewing will also be Wednesday, September 27, 2023, from 9-9:30 AM at the funeral home.\u00a0<br>A mass of Christian burial will be held on Wednesday, September 27, 2023, at 10 AM at Divine Mercy Catholic Church, 203 W Townline St., Payne, Ohio 45880.<br>She will be laid to rest in Lehman Cemetery.\u00a0<br>Memorials may be made to Divine Mercy School.\u00a0<br>Fond memories may be shared at\u00a0<a href=\"http:\/\/dooleyfuneralhome.com\/\">dooleyfuneralhome.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAYNE, OH: Arlette Ann Lopshire, 90, of Payne, passed away Saturday, September 23, 2023, at Vancrest of Payne.Arlette was born<\/p>\n","protected":false},"author":3,"featured_media":41603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[19941,19945,2366,19944,19943,145,19942,8828],"class_list":["post-41602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-obits","tag-arlette-ann-lopshire","tag-david-lopshire","tag-dooley-funeral-home","tag-ernest-lopshire","tag-jimmy-lopshire","tag-lopshire","tag-orlando-james-lopshire","tag-payne-ohio"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Arlette Ann Lopshire | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"318\" \/>\n\t\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-09-25T17:25:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-09-25T17:25:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Arlette Ann Lopshire | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#article\",\"name\":\"Arlette Ann Lopshire | West Bend News\",\"headline\":\"Arlette Ann Lopshire\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Lopshire-obit-copy.jpeg?fit=318%2C457&ssl=1\",\"width\":318,\"height\":457},\"datePublished\":\"2023-09-25T13:25:38-04:00\",\"dateModified\":\"2023-09-25T13:25:40-04:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#webpage\"},\"articleSection\":\"Obituaries, Arlette Ann Lopshire, David Lopshire, Dooley funeral home, Ernest Lopshire, Jimmy Lopshire, Lopshire, Orlando James Lopshire, Payne Ohio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/obits\\\/#listItem\",\"name\":\"Obituaries\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/obits\\\/#listItem\",\"position\":2,\"name\":\"Obituaries\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/obits\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#listItem\",\"name\":\"Arlette Ann Lopshire\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#listItem\",\"position\":3,\"name\":\"Arlette Ann Lopshire\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/obits\\\/#listItem\",\"name\":\"Obituaries\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/\",\"name\":\"Arlette Ann Lopshire | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Lopshire-obit-copy.jpeg?fit=318%2C457&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#mainImage\",\"width\":318,\"height\":457},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/arlette-ann-lopshire\\\/#mainImage\"},\"datePublished\":\"2023-09-25T13:25:38-04:00\",\"dateModified\":\"2023-09-25T13:25:40-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Arlette Ann Lopshire | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#article","name":"Arlette Ann Lopshire | West Bend News","headline":"Arlette Ann Lopshire","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg?fit=318%2C457&ssl=1","width":318,"height":457},"datePublished":"2023-09-25T13:25:38-04:00","dateModified":"2023-09-25T13:25:40-04:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#webpage"},"articleSection":"Obituaries, Arlette Ann Lopshire, David Lopshire, Dooley funeral home, Ernest Lopshire, Jimmy Lopshire, Lopshire, Orlando James Lopshire, Payne Ohio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/obits\/#listItem","name":"Obituaries"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/obits\/#listItem","position":2,"name":"Obituaries","item":"https:\/\/www.westbendnews.net\/autonews\/category\/obits\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#listItem","name":"Arlette Ann Lopshire"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#listItem","position":3,"name":"Arlette Ann Lopshire","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/obits\/#listItem","name":"Obituaries"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/","name":"Arlette Ann Lopshire | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg?fit=318%2C457&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#mainImage","width":318,"height":457},"primaryImageOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/#mainImage"},"datePublished":"2023-09-25T13:25:38-04:00","dateModified":"2023-09-25T13:25:40-04:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"Arlette Ann Lopshire | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/arlette-ann-lopshire\/","og:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg","og:image:secure_url":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg","og:image:width":318,"og:image:height":457,"article:published_time":"2023-09-25T17:25:38+00:00","article:modified_time":"2023-09-25T17:25:40+00:00","twitter:card":"summary","twitter:title":"Arlette Ann Lopshire | West Bend News","twitter:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg"},"aioseo_meta_data":{"post_id":"41602","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-09-25 17:19:26","updated":"2025-06-05 17:04:29","seo_analyzer_scan_date":null},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2023\/09\/Lopshire-obit-copy.jpeg?fit=318%2C457&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-aP0","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:54:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/41602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=41602"}],"version-history":[{"count":1,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/41602\/revisions"}],"predecessor-version":[{"id":41604,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/41602\/revisions\/41604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media\/41603"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=41602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=41602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=41602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}