{"id":29793,"date":"2020-07-16T16:19:23","date_gmt":"2020-07-16T20:19:23","guid":{"rendered":"https:\/\/www.westbendnews.net\/autonews\/?p=29793"},"modified":"2020-07-16T16:19:30","modified_gmt":"2020-07-16T20:19:30","slug":"william-bill-sutton","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/","title":{"rendered":"William &#8220;Bill&#8221; Sutton"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">PAULDING: William \u201cBill\u201d Sutton age 91 died Wednesday, July 15, 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bill was born January 9, 1929 in Paulding, son of the late Lloyd A. and Mary A. (Brenner) Sutton. On December 19, 1952 he married Delores Jean Ames, who preceded him in death on May 2, 2017. He was a US Navy veteran serving during the Korean War and retired from Lafarge. He was a life member of VFW Post #587. He was an avid Ohio State Fan, fisherman and deer hunter, shooting his last deer at age 89.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He is survived by his children: Mary Alice (James) Brown, Pandora, OH, William \u201cBo\u201d (Patricia) Sutton, Hicksville, Lou Ann Bates, Bryan, Danny (Kim) Sutton, and Sally (Chris) Doster, both of Paulding; 11 grandchildren; and 17 great-grandchildren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He is also preceded in death by brother, Lloyd D. Sutton; sisters, Gloria Condon, Kathryn Lewis, Dorothy Thompson; and granddaughter, Miranda Lee Mathews.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Private funeral services will be conducted 2PM Monday, July 20, 220 at Den Herder Funeral Home, Paulding. He will be laid to rest in Live Oak Cemetery with military graveside rites accorded by VFW Post #587.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visitation will be 11 AM until 2 PM Monday, July 20 at Den Herder Funeral Home, Paulding. In the spirit of keeping everyone healthy, the family is requesting that those attending the visitation or service observe wearing face masks and refrain from physical touch&nbsp;while offering the family support.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In lieu of flowers, donations may be made to Tuberous Sclerosis Alliance, 801 Roeder Rd., Suite 750, Silver Springs MD 20910 or Filling Memorial Home of Mercy, N160 St. Rt. 108, Napoleon OH 43545<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Friends are encouraged to share fond memories at www.denherderfh.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAULDING: William \u201cBill\u201d Sutton age 91 died Wednesday, July 15, 2020. Bill was born January 9, 1929 in Paulding, son<\/p>\n","protected":false},"author":3,"featured_media":29795,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-29793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-obits"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"William \u201cBill\u201d Sutton | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2020\/07\/Sutton-William-pic-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2020\/07\/Sutton-William-pic-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"318\" \/>\n\t\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-07-16T20:19:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-07-16T20:19:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/westbendnewspaper\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"William \u201cBill\u201d Sutton | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2020\/07\/Sutton-William-pic-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#article\",\"name\":\"William \\u201cBill\\u201d Sutton | West Bend News\",\"headline\":\"William &#8220;Bill&#8221; Sutton\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Sutton-William-pic-1.jpg?fit=318%2C482&ssl=1\",\"width\":318,\"height\":482},\"datePublished\":\"2020-07-16T16:19:23-04:00\",\"dateModified\":\"2020-07-16T16:19:30-04:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#webpage\"},\"articleSection\":\"Obituaries\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/obits\\\/#listItem\",\"name\":\"Obituaries\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/obits\\\/#listItem\",\"position\":2,\"name\":\"Obituaries\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/obits\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#listItem\",\"name\":\"William &#8220;Bill&#8221; Sutton\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#listItem\",\"position\":3,\"name\":\"William &#8220;Bill&#8221; Sutton\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/obits\\\/#listItem\",\"name\":\"Obituaries\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/westbendnewspaper\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/\",\"name\":\"William \\u201cBill\\u201d Sutton | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Sutton-William-pic-1.jpg?fit=318%2C482&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#mainImage\",\"width\":318,\"height\":482},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/william-bill-sutton\\\/#mainImage\"},\"datePublished\":\"2020-07-16T16:19:23-04:00\",\"dateModified\":\"2020-07-16T16:19:30-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"William \u201cBill\u201d Sutton | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#article","name":"William \u201cBill\u201d Sutton | West Bend News","headline":"William &#8220;Bill&#8221; Sutton","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2020\/07\/Sutton-William-pic-1.jpg?fit=318%2C482&ssl=1","width":318,"height":482},"datePublished":"2020-07-16T16:19:23-04:00","dateModified":"2020-07-16T16:19:30-04:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#webpage"},"articleSection":"Obituaries"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/obits\/#listItem","name":"Obituaries"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/obits\/#listItem","position":2,"name":"Obituaries","item":"https:\/\/www.westbendnews.net\/autonews\/category\/obits\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#listItem","name":"William &#8220;Bill&#8221; Sutton"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#listItem","position":3,"name":"William &#8220;Bill&#8221; Sutton","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/obits\/#listItem","name":"Obituaries"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/westbendnewspaper"]},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/","name":"William \u201cBill\u201d Sutton | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2020\/07\/Sutton-William-pic-1.jpg?fit=318%2C482&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#mainImage","width":318,"height":482},"primaryImageOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/#mainImage"},"datePublished":"2020-07-16T16:19:23-04:00","dateModified":"2020-07-16T16:19:30-04:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"William \u201cBill\u201d Sutton | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/william-bill-sutton\/","og:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2020\/07\/Sutton-William-pic-1.jpg","og:image:secure_url":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2020\/07\/Sutton-William-pic-1.jpg","og:image:width":318,"og:image:height":482,"article:published_time":"2020-07-16T20:19:23+00:00","article:modified_time":"2020-07-16T20:19:30+00:00","article:publisher":"https:\/\/www.facebook.com\/westbendnewspaper","twitter:card":"summary","twitter:title":"William \u201cBill\u201d Sutton | West Bend News","twitter:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2020\/07\/Sutton-William-pic-1.jpg"},"aioseo_meta_data":{"post_id":"29793","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-06 19:48:54","updated":"2025-06-05 04:47:20","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-7Kx","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 00:38:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2020\/07\/Sutton-William-pic-1.jpg?fit=318%2C482&ssl=1","_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/29793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=29793"}],"version-history":[{"count":0,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/29793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media\/29795"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=29793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=29793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=29793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}