{"id":25377,"date":"2019-04-07T04:36:41","date_gmt":"2019-04-07T08:36:41","guid":{"rendered":"https:\/\/www.westbendnews.net\/autonews\/?p=25377"},"modified":"2019-04-03T16:43:08","modified_gmt":"2019-04-03T20:43:08","slug":"kiwanis-talks-about-national-child-abuse-awareness-month","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/","title":{"rendered":"Kiwanis talks about National Child Abuse Awareness Month"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"666\" height=\"344\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg?resize=666%2C344&#038;ssl=1\" alt=\"\" class=\"wp-image-25378\" srcset=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg?w=666&amp;ssl=1 666w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg?resize=560%2C289&amp;ssl=1 560w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg?resize=260%2C134&amp;ssl=1 260w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg?resize=160%2C83&amp;ssl=1 160w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><figcaption><strong>Pictured is Taryn Stiltner, director of United Way of Paulding County.<\/strong><br><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">The director of United Way of Paulding County, and Kiwanis member Taryn Stiltner spoke about Ohio Children\u2019s Trust Fund Council at Kiwanis\u2019 most recent meeting. Stiltner is a board member of the council and has served for a little over a year. The Council focuses on preventing abuse and neglect by investing in the community through programs and services. April is National Child Abuse Awareness Month. \u201cMany times, child abuse and neglect are related to substance abuse,\u201d says Stiltner. KeepaPromise.org is a great resource if you know of a child or parent that is struggling with abuse. The site can connect you to the resources and opportunities in your county. Stiltner talked briefly about a program called Parent Caf\u00e9 that helps to bring awareness to parents about this issue. If interested in learning more, or how you can help call Taryn at 419-399-8240. Kiwanis thanks Taryn for her dedication and love for the children of our county. Kiwanis members will meet Thursday over lunch.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The director of United Way of Paulding County, and Kiwanis member Taryn Stiltner spoke about Ohio Children\u2019s Trust Fund Council<\/p>\n","protected":false},"author":3,"featured_media":25378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2230,6,2301,499],"tags":[748,12095,12096],"class_list":["post-25377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-community","category-community","category-general-news","category-health","tag-abuse","tag-neglect","tag-parent-cafe"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Kiwanis talks about National Child Abuse Awareness Month | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"666\" \/>\n\t\t<meta property=\"og:image:height\" content=\"344\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-04-07T08:36:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-03T20:43:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Kiwanis talks about National Child Abuse Awareness Month | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#article\",\"name\":\"Kiwanis talks about National Child Abuse Awareness Month | West Bend News\",\"headline\":\"Kiwanis talks about National Child Abuse Awareness Month\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Kiwanis.jpg?fit=666%2C344&ssl=1\",\"width\":666,\"height\":344},\"datePublished\":\"2019-04-07T04:36:41-04:00\",\"dateModified\":\"2019-04-03T16:43:08-04:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#webpage\"},\"articleSection\":\"Business, Community, General News, Health, abuse, neglect, Parent Caf\\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/#listItem\",\"name\":\"Community\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/#listItem\",\"position\":2,\"name\":\"Community\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/business-community\\\/#listItem\",\"name\":\"Business\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/business-community\\\/#listItem\",\"position\":3,\"name\":\"Business\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/business-community\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#listItem\",\"name\":\"Kiwanis talks about National Child Abuse Awareness Month\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/#listItem\",\"name\":\"Community\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#listItem\",\"position\":4,\"name\":\"Kiwanis talks about National Child Abuse Awareness Month\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/business-community\\\/#listItem\",\"name\":\"Business\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/\",\"name\":\"Kiwanis talks about National Child Abuse Awareness Month | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Kiwanis.jpg?fit=666%2C344&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#mainImage\",\"width\":666,\"height\":344},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/kiwanis-talks-about-national-child-abuse-awareness-month\\\/#mainImage\"},\"datePublished\":\"2019-04-07T04:36:41-04:00\",\"dateModified\":\"2019-04-03T16:43:08-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Kiwanis talks about National Child Abuse Awareness Month | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#article","name":"Kiwanis talks about National Child Abuse Awareness Month | West Bend News","headline":"Kiwanis talks about National Child Abuse Awareness Month","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg?fit=666%2C344&ssl=1","width":666,"height":344},"datePublished":"2019-04-07T04:36:41-04:00","dateModified":"2019-04-03T16:43:08-04:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#webpage"},"articleSection":"Business, Community, General News, Health, abuse, neglect, Parent Caf\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/#listItem","name":"Community"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/#listItem","position":2,"name":"Community","item":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/business-community\/#listItem","name":"Business"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/business-community\/#listItem","position":3,"name":"Business","item":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/business-community\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#listItem","name":"Kiwanis talks about National Child Abuse Awareness Month"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/#listItem","name":"Community"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#listItem","position":4,"name":"Kiwanis talks about National Child Abuse Awareness Month","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/business-community\/#listItem","name":"Business"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/","name":"Kiwanis talks about National Child Abuse Awareness Month | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg?fit=666%2C344&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#mainImage","width":666,"height":344},"primaryImageOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/#mainImage"},"datePublished":"2019-04-07T04:36:41-04:00","dateModified":"2019-04-03T16:43:08-04:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"Kiwanis talks about National Child Abuse Awareness Month | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/kiwanis-talks-about-national-child-abuse-awareness-month\/","og:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg","og:image:secure_url":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg","og:image:width":666,"og:image:height":344,"article:published_time":"2019-04-07T08:36:41+00:00","article:modified_time":"2019-04-03T20:43:08+00:00","twitter:card":"summary","twitter:title":"Kiwanis talks about National Child Abuse Awareness Month | West Bend News","twitter:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg"},"aioseo_meta_data":{"post_id":"25377","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-06 20:41:43","updated":"2025-06-05 03:02:22","seo_analyzer_scan_date":null},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/04\/Kiwanis.jpg?fit=666%2C344&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-6Bj","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:00:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/25377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=25377"}],"version-history":[{"count":0,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/25377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media\/25378"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=25377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=25377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=25377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}