{"id":25270,"date":"2019-03-26T07:33:53","date_gmt":"2019-03-26T11:33:53","guid":{"rendered":"https:\/\/www.westbendnews.net\/autonews\/?p=25270"},"modified":"2019-03-21T09:04:48","modified_gmt":"2019-03-21T13:04:48","slug":"2019-lgoc-newly-elected-officials","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/","title":{"rendered":"2019 LGOC Newly Elected Officials"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"487\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg?resize=800%2C487&#038;ssl=1\" alt=\"\" class=\"wp-image-25271\" srcset=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg?w=1016&amp;ssl=1 1016w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg?resize=768%2C468&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg?resize=560%2C341&amp;ssl=1 560w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg?resize=260%2C158&amp;ssl=1 260w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg?resize=160%2C97&amp;ssl=1 160w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Newly elected Ohio State Auditor, Keith Faber, was the featured speaker at the 2019 Local Government Officials Conference held in Columbus, Ohio March 6-8, 2019. Pictured from left to right are Chris Ferris (Brunersburg Water Fiscal Officer), Jane Buchman (Paulding Twp Fiscal Officer), Keith Faber, Racheal Head (Benton Twp Fiscal Officer), Sue Becher (Auglaize Twp Fiscal Officer) and Kathy Feasby (Harrison Twp Fiscal Officer).<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Newly elected Ohio State Auditor, Keith Faber, was the featured speaker at the 2019 Local Government Officials Conference held in<\/p>\n","protected":false},"author":3,"featured_media":25271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2230,6,92,2301],"tags":[12020],"class_list":["post-25270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-community","category-community","category-election","category-general-news","tag-local-government-officials-conference"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"2019 LGOC Newly Elected Officials | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1016\" \/>\n\t\t<meta property=\"og:image:height\" content=\"619\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-03-26T11:33:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-03-21T13:04:48+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/westbendnewspaper\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"2019 LGOC Newly Elected Officials | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#article\",\"name\":\"2019 LGOC Newly Elected Officials | West Bend News\",\"headline\":\"2019 LGOC Newly Elected Officials\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Fiscal-officers.jpg?fit=1016%2C619&ssl=1\",\"width\":1016,\"height\":619},\"datePublished\":\"2019-03-26T07:33:53-04:00\",\"dateModified\":\"2019-03-21T09:04:48-04:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#webpage\"},\"articleSection\":\"Business, Community, Election, General News, Local Government Officials Conference\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/government-legal\\\/#listItem\",\"name\":\"Legal\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/government-legal\\\/#listItem\",\"position\":2,\"name\":\"Legal\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/government-legal\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/government-legal\\\/election\\\/#listItem\",\"name\":\"Election\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/government-legal\\\/election\\\/#listItem\",\"position\":3,\"name\":\"Election\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/government-legal\\\/election\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#listItem\",\"name\":\"2019 LGOC Newly Elected Officials\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/government-legal\\\/#listItem\",\"name\":\"Legal\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#listItem\",\"position\":4,\"name\":\"2019 LGOC Newly Elected Officials\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/government-legal\\\/election\\\/#listItem\",\"name\":\"Election\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/westbendnewspaper\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/\",\"name\":\"2019 LGOC Newly Elected Officials | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Fiscal-officers.jpg?fit=1016%2C619&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#mainImage\",\"width\":1016,\"height\":619},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/2019-lgoc-newly-elected-officials\\\/#mainImage\"},\"datePublished\":\"2019-03-26T07:33:53-04:00\",\"dateModified\":\"2019-03-21T09:04:48-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"2019 LGOC Newly Elected Officials | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#article","name":"2019 LGOC Newly Elected Officials | West Bend News","headline":"2019 LGOC Newly Elected Officials","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg?fit=1016%2C619&ssl=1","width":1016,"height":619},"datePublished":"2019-03-26T07:33:53-04:00","dateModified":"2019-03-21T09:04:48-04:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#webpage"},"articleSection":"Business, Community, Election, General News, Local Government Officials Conference"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/government-legal\/#listItem","name":"Legal"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/government-legal\/#listItem","position":2,"name":"Legal","item":"https:\/\/www.westbendnews.net\/autonews\/category\/government-legal\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/government-legal\/election\/#listItem","name":"Election"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/government-legal\/election\/#listItem","position":3,"name":"Election","item":"https:\/\/www.westbendnews.net\/autonews\/category\/government-legal\/election\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#listItem","name":"2019 LGOC Newly Elected Officials"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/government-legal\/#listItem","name":"Legal"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#listItem","position":4,"name":"2019 LGOC Newly Elected Officials","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/government-legal\/election\/#listItem","name":"Election"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/westbendnewspaper"]},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/","name":"2019 LGOC Newly Elected Officials | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg?fit=1016%2C619&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#mainImage","width":1016,"height":619},"primaryImageOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/#mainImage"},"datePublished":"2019-03-26T07:33:53-04:00","dateModified":"2019-03-21T09:04:48-04:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"2019 LGOC Newly Elected Officials | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/2019-lgoc-newly-elected-officials\/","og:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg","og:image:secure_url":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg","og:image:width":1016,"og:image:height":619,"article:published_time":"2019-03-26T11:33:53+00:00","article:modified_time":"2019-03-21T13:04:48+00:00","article:publisher":"https:\/\/www.facebook.com\/westbendnewspaper","twitter:card":"summary","twitter:title":"2019 LGOC Newly Elected Officials | West Bend News","twitter:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg"},"aioseo_meta_data":{"post_id":"25270","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-06 20:42:41","updated":"2025-06-05 02:59:21","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-6zA","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:00:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2019\/03\/Fiscal-officers.jpg?fit=1016%2C619&ssl=1","_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/25270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=25270"}],"version-history":[{"count":0,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/25270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media\/25271"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=25270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=25270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=25270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}