{"id":24131,"date":"2018-11-18T16:30:45","date_gmt":"2018-11-18T21:30:45","guid":{"rendered":"https:\/\/www.westbendnews.net\/autonews\/?p=24131"},"modified":"2018-11-15T09:43:00","modified_gmt":"2018-11-15T14:43:00","slug":"fulk-named-winner-of-wendys-high-scholarship-competition","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/","title":{"rendered":"Fulk named winner of Wendy\u2019s High Scholarship Competition"},"content":{"rendered":"<figure id=\"attachment_24132\" aria-describedby=\"caption-attachment-24132\" style=\"width: 316px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-24132\" src=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg?resize=316%2C419&#038;ssl=1\" alt=\"\" width=\"316\" height=\"419\" srcset=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg?w=316&amp;ssl=1 316w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg?resize=260%2C345&amp;ssl=1 260w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg?resize=160%2C212&amp;ssl=1 160w\" sizes=\"auto, (max-width: 316px) 100vw, 316px\" \/><\/a><figcaption id=\"caption-attachment-24132\" class=\"wp-caption-text\">Brett Fulk<\/figcaption><\/figure>\n<p>Brett Fulk, a senior at Antwerp High School, was recently named the school winner in the Wendy\u2019s High School Heisman Scholarship Competition. To apply for this, students must be graduating with the class of 2019, have a cumulative high school grade point average of a B (3.0) or better, participate in at least one of the 47 sports recognized by the National Federation of State High School Association and be a leader in his\/her school and community.<\/p>\n<p>The Wendy\u2019s High School Heisman was created by Wendy\u2019s founder Dave Thomas in 1994.<span class=\"Apple-converted-space\">\u00a0 <\/span>Dave Thomas dropped out of high school when he was 15 years old in order to work full-time and went on to become one of the most successful entrepreneurs in history.<span class=\"Apple-converted-space\">\u00a0 <\/span>While this nontraditional path led to his prosperity, it always worried Dave that others would follow in his footsteps and expect to achieve similar fame and wealth by not finishing high school or attending college.<\/p>\n<p>Faced with this dilemma, at 61 years old, Dave enrolled at Coconut Creek High School in Ft. Lauderdale, Fla., and received his General Equivalency Diploma (GED). Inspired by this moment and with a desire to celebrate the outstanding achievements of youth in America, he launched the Wendy\u2019s High School Heisman program.<\/p>\n<p>Twenty-five years later, Wendy\u2019s High School Heisman has honored more than 600,000 of the nation\u2019s most esteemed high school seniors who share Wendy\u2019s values of giving back to their communities, treating people with respect, continuing education and excelling on the athletic field.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brett Fulk, a senior at Antwerp High School, was recently named the school winner in the Wendy\u2019s High School Heisman<\/p>\n","protected":false},"author":3,"featured_media":24132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[3019,11412,11414,11413],"class_list":["post-24131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports","tag-antwerp-high-school","tag-brett-fulk","tag-dave-thomas","tag-wendys-high-school-heisman"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fulk named winner of Wendy\u2019s High Scholarship Competition | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"316\" \/>\n\t\t<meta property=\"og:image:height\" content=\"419\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-11-18T21:30:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-11-15T14:43:00+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/westbendnewspaper\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fulk named winner of Wendy\u2019s High Scholarship Competition | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#article\",\"name\":\"Fulk named winner of Wendy\\u2019s High Scholarship Competition | West Bend News\",\"headline\":\"Fulk named winner of Wendy\\u2019s High Scholarship Competition\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Brett-Fulk.jpg?fit=316%2C419&ssl=1\",\"width\":316,\"height\":419,\"caption\":\"Brett Fulk\"},\"datePublished\":\"2018-11-18T16:30:45-05:00\",\"dateModified\":\"2018-11-15T09:43:00-05:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#webpage\"},\"articleSection\":\"Sports, antwerp high school, Brett Fulk, Dave Thomas, Wendy\\u2019s High School Heisman\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/sports\\\/#listItem\",\"name\":\"Sports\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/sports\\\/#listItem\",\"position\":2,\"name\":\"Sports\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/sports\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#listItem\",\"name\":\"Fulk named winner of Wendy\\u2019s High Scholarship Competition\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#listItem\",\"position\":3,\"name\":\"Fulk named winner of Wendy\\u2019s High Scholarship Competition\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/sports\\\/#listItem\",\"name\":\"Sports\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/westbendnewspaper\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/\",\"name\":\"Fulk named winner of Wendy\\u2019s High Scholarship Competition | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Brett-Fulk.jpg?fit=316%2C419&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#mainImage\",\"width\":316,\"height\":419,\"caption\":\"Brett Fulk\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/fulk-named-winner-of-wendys-high-scholarship-competition\\\/#mainImage\"},\"datePublished\":\"2018-11-18T16:30:45-05:00\",\"dateModified\":\"2018-11-15T09:43:00-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fulk named winner of Wendy\u2019s High Scholarship Competition | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#article","name":"Fulk named winner of Wendy\u2019s High Scholarship Competition | West Bend News","headline":"Fulk named winner of Wendy\u2019s High Scholarship Competition","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg?fit=316%2C419&ssl=1","width":316,"height":419,"caption":"Brett Fulk"},"datePublished":"2018-11-18T16:30:45-05:00","dateModified":"2018-11-15T09:43:00-05:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#webpage"},"articleSection":"Sports, antwerp high school, Brett Fulk, Dave Thomas, Wendy\u2019s High School Heisman"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/sports\/#listItem","name":"Sports"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/sports\/#listItem","position":2,"name":"Sports","item":"https:\/\/www.westbendnews.net\/autonews\/category\/sports\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#listItem","name":"Fulk named winner of Wendy\u2019s High Scholarship Competition"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#listItem","position":3,"name":"Fulk named winner of Wendy\u2019s High Scholarship Competition","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/sports\/#listItem","name":"Sports"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/westbendnewspaper"]},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/","name":"Fulk named winner of Wendy\u2019s High Scholarship Competition | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg?fit=316%2C419&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#mainImage","width":316,"height":419,"caption":"Brett Fulk"},"primaryImageOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/#mainImage"},"datePublished":"2018-11-18T16:30:45-05:00","dateModified":"2018-11-15T09:43:00-05:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"Fulk named winner of Wendy\u2019s High Scholarship Competition | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/fulk-named-winner-of-wendys-high-scholarship-competition\/","og:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg","og:image:secure_url":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg","og:image:width":316,"og:image:height":419,"article:published_time":"2018-11-18T21:30:45+00:00","article:modified_time":"2018-11-15T14:43:00+00:00","article:publisher":"https:\/\/www.facebook.com\/westbendnewspaper","twitter:card":"summary","twitter:title":"Fulk named winner of Wendy\u2019s High Scholarship Competition | West Bend News","twitter:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg"},"aioseo_meta_data":{"post_id":"24131","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-06 20:54:21","updated":"2025-06-05 02:29:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-6hd","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:40:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/11\/Brett-Fulk.jpg?fit=316%2C419&ssl=1","_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/24131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=24131"}],"version-history":[{"count":0,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/24131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media\/24132"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=24131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=24131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=24131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}