{"id":23465,"date":"2018-09-20T12:00:06","date_gmt":"2018-09-20T16:00:06","guid":{"rendered":"https:\/\/www.westbendnews.net\/autonews\/?p=23465"},"modified":"2018-09-19T11:39:53","modified_gmt":"2018-09-19T15:39:53","slug":"hahn-berenyi","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/","title":{"rendered":"Hahn \u2013 Berenyi"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-23466\" src=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg?resize=666%2C896&#038;ssl=1\" alt=\"\" width=\"666\" height=\"896\" srcset=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg?w=666&amp;ssl=1 666w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg?resize=560%2C753&amp;ssl=1 560w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg?resize=260%2C350&amp;ssl=1 260w, https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg?resize=160%2C215&amp;ssl=1 160w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/>Morgan Hahn, daughter of Dan and Karen Hahn of Antwerp, and Cole Berenyi, son of Gabe Berenyi (Amy Kreg) of Hicksville and Amy Karacson (John) of Mark Center, are happy to announce their engagement and forthcoming marriage. Morgan is a graduate of Northwest State Community College, majoring in Graphic Design, and Cole is a machinist at B &amp; J Specialty in Wawaka, Indiana. The couple will be united in marriage on Saturday, September 22, 2018. They will reside in Avilla, Indiana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morgan Hahn, daughter of Dan and Karen Hahn of Antwerp, and Cole Berenyi, son of Gabe Berenyi (Amy Kreg) of<\/p>\n","protected":false},"author":3,"featured_media":23466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6,1854],"tags":[11060,728,1124,66],"class_list":["post-23465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-community","category-weddings","tag-berenyi","tag-engagement","tag-hahn","tag-wedding"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hahn \u2013 Berenyi | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"666\" \/>\n\t\t<meta property=\"og:image:height\" content=\"896\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-09-20T16:00:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-09-19T15:39:53+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/westbendnewspaper\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hahn \u2013 Berenyi | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#article\",\"name\":\"Hahn \\u2013 Berenyi | West Bend News\",\"headline\":\"Hahn \\u2013 Berenyi\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Hahn-Berenyi.jpeg?fit=666%2C896&ssl=1\",\"width\":666,\"height\":896},\"datePublished\":\"2018-09-20T12:00:06-04:00\",\"dateModified\":\"2018-09-19T11:39:53-04:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#webpage\"},\"articleSection\":\"Community, Engagements and Weddings, Berenyi, Engagement, hahn, wedding\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/#listItem\",\"name\":\"Community\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/#listItem\",\"position\":2,\"name\":\"Community\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/weddings\\\/#listItem\",\"name\":\"Engagements and Weddings\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/weddings\\\/#listItem\",\"position\":3,\"name\":\"Engagements and Weddings\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/weddings\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#listItem\",\"name\":\"Hahn \\u2013 Berenyi\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/#listItem\",\"name\":\"Community\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#listItem\",\"position\":4,\"name\":\"Hahn \\u2013 Berenyi\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/community\\\/weddings\\\/#listItem\",\"name\":\"Engagements and Weddings\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/westbendnewspaper\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/\",\"name\":\"Hahn \\u2013 Berenyi | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Hahn-Berenyi.jpeg?fit=666%2C896&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#mainImage\",\"width\":666,\"height\":896},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/hahn-berenyi\\\/#mainImage\"},\"datePublished\":\"2018-09-20T12:00:06-04:00\",\"dateModified\":\"2018-09-19T11:39:53-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Hahn \u2013 Berenyi | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#article","name":"Hahn \u2013 Berenyi | West Bend News","headline":"Hahn \u2013 Berenyi","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg?fit=666%2C896&ssl=1","width":666,"height":896},"datePublished":"2018-09-20T12:00:06-04:00","dateModified":"2018-09-19T11:39:53-04:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#webpage"},"articleSection":"Community, Engagements and Weddings, Berenyi, Engagement, hahn, wedding"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/#listItem","name":"Community"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/#listItem","position":2,"name":"Community","item":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/weddings\/#listItem","name":"Engagements and Weddings"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/weddings\/#listItem","position":3,"name":"Engagements and Weddings","item":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/weddings\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#listItem","name":"Hahn \u2013 Berenyi"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/#listItem","name":"Community"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#listItem","position":4,"name":"Hahn \u2013 Berenyi","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/community\/weddings\/#listItem","name":"Engagements and Weddings"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/westbendnewspaper"]},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/","name":"Hahn \u2013 Berenyi | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg?fit=666%2C896&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#mainImage","width":666,"height":896},"primaryImageOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/#mainImage"},"datePublished":"2018-09-20T12:00:06-04:00","dateModified":"2018-09-19T11:39:53-04:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"Hahn \u2013 Berenyi | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/hahn-berenyi\/","og:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg","og:image:secure_url":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg","og:image:width":666,"og:image:height":896,"article:published_time":"2018-09-20T16:00:06+00:00","article:modified_time":"2018-09-19T15:39:53+00:00","article:publisher":"https:\/\/www.facebook.com\/westbendnewspaper","twitter:card":"summary","twitter:title":"Hahn \u2013 Berenyi | West Bend News","twitter:image":"https:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg"},"aioseo_meta_data":{"post_id":"23465","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-06 21:05:40","updated":"2025-06-05 02:09:20","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-66t","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 13:29:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2018\/09\/Hahn-Berenyi.jpeg?fit=666%2C896&ssl=1","_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/23465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=23465"}],"version-history":[{"count":0,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/23465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media\/23466"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=23465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=23465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=23465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}