{"id":18782,"date":"2017-09-04T09:26:57","date_gmt":"2017-09-04T13:26:57","guid":{"rendered":"http:\/\/www.westbendnews.net\/autonews\/?p=18782"},"modified":"2017-08-29T08:32:05","modified_gmt":"2017-08-29T12:32:05","slug":"village-trash-pick-up-will-be-a-day-behind-next-week","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/","title":{"rendered":"Village Trash Pick Up Will Be A Day Behind Next Week"},"content":{"rendered":"<p>Village trash pick up will be one day behind due to Labor Day.\u00a0 Pick will be on Friday, September 8th.\u00a0 It is the first pick up of the month so will be big pick up day.\u00a0 If you ever have questions on what Real Waste will pick up, please call Real Waste direct at 419-594-2888.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Village trash pick up will be one day behind due to Labor Day.\u00a0 Pick will be on Friday, September 8th.\u00a0<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2301],"tags":[218,5978,5780,8459,8456,3885,12,8458,8461,1522,8460,8457],"class_list":["post-18782","post","type-post","status-publish","format-standard","hentry","category-general-news","tag-antwerp","tag-antwerp-village","tag-labor-day","tag-late","tag-late-trash-pick-up","tag-oh","tag-ohio","tag-one-day-behind","tag-real-waste","tag-september","tag-september-8","tag-trash-pick-up"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Village Trash Pick Up Will Be A Day Behind Next Week | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-09-04T13:26:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-08-29T12:32:05+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Village Trash Pick Up Will Be A Day Behind Next Week | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&amp;ssl=1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#article\",\"name\":\"Village Trash Pick Up Will Be A Day Behind Next Week | West Bend News\",\"headline\":\"Village Trash Pick Up Will Be A Day Behind Next Week\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#articleImage\",\"width\":1067,\"height\":206},\"datePublished\":\"2017-09-04T09:26:57-04:00\",\"dateModified\":\"2017-08-29T08:32:05-04:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#webpage\"},\"articleSection\":\"General News, Antwerp, Antwerp Village, labor day, Late, Late Trash Pick up, OH, Ohio, One day behind, Real Waste, september, September 8, Trash Pick-up\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/general-news\\\/#listItem\",\"name\":\"General News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/general-news\\\/#listItem\",\"position\":2,\"name\":\"General News\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/general-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#listItem\",\"name\":\"Village Trash Pick Up Will Be A Day Behind Next Week\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#listItem\",\"position\":3,\"name\":\"Village Trash Pick Up Will Be A Day Behind Next Week\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/general-news\\\/#listItem\",\"name\":\"General News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/\",\"name\":\"Village Trash Pick Up Will Be A Day Behind Next Week | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/village-trash-pick-up-will-be-a-day-behind-next-week\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"datePublished\":\"2017-09-04T09:26:57-04:00\",\"dateModified\":\"2017-08-29T08:32:05-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Village Trash Pick Up Will Be A Day Behind Next Week | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#article","name":"Village Trash Pick Up Will Be A Day Behind Next Week | West Bend News","headline":"Village Trash Pick Up Will Be A Day Behind Next Week","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/#articleImage","width":1067,"height":206},"datePublished":"2017-09-04T09:26:57-04:00","dateModified":"2017-08-29T08:32:05-04:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#webpage"},"articleSection":"General News, Antwerp, Antwerp Village, labor day, Late, Late Trash Pick up, OH, Ohio, One day behind, Real Waste, september, September 8, Trash Pick-up"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/general-news\/#listItem","name":"General News"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/general-news\/#listItem","position":2,"name":"General News","item":"https:\/\/www.westbendnews.net\/autonews\/category\/general-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#listItem","name":"Village Trash Pick Up Will Be A Day Behind Next Week"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#listItem","position":3,"name":"Village Trash Pick Up Will Be A Day Behind Next Week","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/general-news\/#listItem","name":"General News"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/","name":"Village Trash Pick Up Will Be A Day Behind Next Week | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"datePublished":"2017-09-04T09:26:57-04:00","dateModified":"2017-08-29T08:32:05-04:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"Village Trash Pick Up Will Be A Day Behind Next Week | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/village-trash-pick-up-will-be-a-day-behind-next-week\/","og:image":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1","og:image:secure_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1","article:published_time":"2017-09-04T13:26:57+00:00","article:modified_time":"2017-08-29T12:32:05+00:00","twitter:card":"summary","twitter:title":"Village Trash Pick Up Will Be A Day Behind Next Week | West Bend News","twitter:image":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&ssl=1"},"aioseo_meta_data":{"post_id":"18782","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-06 20:42:42","updated":"2025-06-05 00:04:32","seo_analyzer_scan_date":null},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-4SW","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-21 20:30:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/18782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=18782"}],"version-history":[{"count":0,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/18782\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=18782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=18782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=18782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}