{"id":18364,"date":"2017-07-24T07:17:10","date_gmt":"2017-07-24T11:17:10","guid":{"rendered":"http:\/\/www.westbendnews.net\/autonews\/?p=18364"},"modified":"2017-07-18T10:24:55","modified_gmt":"2017-07-18T14:24:55","slug":"local-resident-graduates-from-highway-patrol-junior-cadet-program","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/","title":{"rendered":"Local Resident Graduates From Highway Patrol Junior Cadet Program"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-18365\" src=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2017\/07\/Junior-Cadet.jpg?resize=667%2C644\" alt=\"\" width=\"667\" height=\"644\" \/>A local resident completed training today for the Ohio State Highway Patrol\u2019s Junior Cadet Program held June 25-29, 2017 at the Highway Patrol Training Academy in Columbus. A local resident, Koleton Porter, was one of 40 Junior Cadet participants selected from applications submitted by young men and women who attended Buckeye Boys and Girls State earlier this month, exhibited exemplary performance throughout the previous school year, or eligible children of Patrol employees who will be high school seniors this year.<\/p>\n<p>The Junior Cadet Program is designed to give young people better insight into the challenges faced by law enforcement officers by enabling them to experience a typical week at the Training Academy. To enhance their learning experience, Junior Cadets are required to stay at the Training Academy, sleeping in the dormitories and dining in the cafeteria. While at the Academy, they gain knowledge from Patrol Academy staff regarding crash investigation, officer\/violator contacts, self-defense tactics, K-9 operations, emergency vehicle operations, motorcycle operations, impaired driver apprehension and military drill.<\/p>\n<p>Colonel Paul A. Pride, Superintendent, presented graduation certificates to the young men and women who participated in the Junior Cadet Program at a ceremony held today at the Training Academy. Family and friends of the cadets were also in attendance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A local resident completed training today for the Ohio State Highway Patrol\u2019s Junior Cadet Program held June 25-29, 2017 at<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[6437,218,7755,7751,7754,926,7749,921,7753,7750,3396,7374,3885,12,5264,7752],"class_list":["post-18364","post","type-post","status-publish","format-standard","hentry","category-school","tag-6437","tag-antwerp","tag-buckeye-boys","tag-challenges","tag-emergency-vehicle-operations","tag-graduates","tag-highway-patrol-junior-cadet-program","tag-june","tag-k-9-operations","tag-koleton-porter","tag-law-enforcement","tag-local-resident","tag-oh","tag-ohio","tag-ohio-state","tag-patrol-academy"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Local Resident Graduates From Highway Patrol Junior Cadet Program | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-24T11:17:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-18T14:24:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Local Resident Graduates From Highway Patrol Junior Cadet Program | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&amp;ssl=1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#article\",\"name\":\"Local Resident Graduates From Highway Patrol Junior Cadet Program | West Bend News\",\"headline\":\"Local Resident Graduates From Highway Patrol Junior Cadet Program\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Junior-Cadet.jpg\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#articleImage\"},\"datePublished\":\"2017-07-24T07:17:10-04:00\",\"dateModified\":\"2017-07-18T10:24:55-04:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#webpage\"},\"articleSection\":\"School, 2017, Antwerp, Buckeye Boys, Challenges, emergency vehicle operations, graduates, Highway Patrol Junior Cadet Program, June, k-9 operations, Koleton Porter, Law enforcement, Local resident, OH, Ohio, Ohio State, Patrol Academy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/school\\\/#listItem\",\"name\":\"School\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/school\\\/#listItem\",\"position\":2,\"name\":\"School\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/school\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#listItem\",\"name\":\"Local Resident Graduates From Highway Patrol Junior Cadet Program\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#listItem\",\"position\":3,\"name\":\"Local Resident Graduates From Highway Patrol Junior Cadet Program\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/school\\\/#listItem\",\"name\":\"School\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/\",\"name\":\"Local Resident Graduates From Highway Patrol Junior Cadet Program | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/local-resident-graduates-from-highway-patrol-junior-cadet-program\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"datePublished\":\"2017-07-24T07:17:10-04:00\",\"dateModified\":\"2017-07-18T10:24:55-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Local Resident Graduates From Highway Patrol Junior Cadet Program | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#article","name":"Local Resident Graduates From Highway Patrol Junior Cadet Program | West Bend News","headline":"Local Resident Graduates From Highway Patrol Junior Cadet Program","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2017\/07\/Junior-Cadet.jpg","@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#articleImage"},"datePublished":"2017-07-24T07:17:10-04:00","dateModified":"2017-07-18T10:24:55-04:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#webpage"},"articleSection":"School, 2017, Antwerp, Buckeye Boys, Challenges, emergency vehicle operations, graduates, Highway Patrol Junior Cadet Program, June, k-9 operations, Koleton Porter, Law enforcement, Local resident, OH, Ohio, Ohio State, Patrol Academy"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/school\/#listItem","name":"School"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/school\/#listItem","position":2,"name":"School","item":"https:\/\/www.westbendnews.net\/autonews\/category\/school\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#listItem","name":"Local Resident Graduates From Highway Patrol Junior Cadet Program"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#listItem","position":3,"name":"Local Resident Graduates From Highway Patrol Junior Cadet Program","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/school\/#listItem","name":"School"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/","name":"Local Resident Graduates From Highway Patrol Junior Cadet Program | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"datePublished":"2017-07-24T07:17:10-04:00","dateModified":"2017-07-18T10:24:55-04:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"Local Resident Graduates From Highway Patrol Junior Cadet Program | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/local-resident-graduates-from-highway-patrol-junior-cadet-program\/","og:image":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1","og:image:secure_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1","article:published_time":"2017-07-24T11:17:10+00:00","article:modified_time":"2017-07-18T14:24:55+00:00","twitter:card":"summary","twitter:title":"Local Resident Graduates From Highway Patrol Junior Cadet Program | West Bend News","twitter:image":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&ssl=1"},"aioseo_meta_data":{"post_id":"18364","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-06 20:39:56","updated":"2025-06-04 23:50:50","seo_analyzer_scan_date":null},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-4Mc","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-21 21:40:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/18364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=18364"}],"version-history":[{"count":0,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/18364\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=18364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=18364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=18364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}