{"id":18094,"date":"2017-07-01T07:30:27","date_gmt":"2017-07-01T11:30:27","guid":{"rendered":"http:\/\/www.westbendnews.net\/autonews\/?p=18094"},"modified":"2017-06-27T09:04:42","modified_gmt":"2017-06-27T13:04:42","slug":"north-scipio-veteran-memorial","status":"publish","type":"post","link":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/","title":{"rendered":"North Scipio Veteran Memorial"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-18096\" src=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2017\/06\/North-Scipio-Veterans-Memorial-2.jpg?resize=402%2C473\" alt=\"\" width=\"402\" height=\"473\" \/>It is the honor and duty, that we (the North Scipio Memorial Committee) feel the Lord lead us to establish the memorial for the purposes of prayers, healing and remembrance of those who have served God and country, and to preserve our basic freedoms, especially the right to worship and proudly wave our American flag.<\/p>\n<p>Please drive past the memorial or stop to pray or worship. Tell your friends about the memorial. Finally, help those who have not resolved the pain of their service, by asking God to intervene and heal their pain and bring them peace.<\/p>\n<p>\u2013Gratefully submitted by the North Scipio Memorial Committee<\/p>\n","protected":false},"excerpt":{"rendered":"<p>It is the honor and duty, that we (the North Scipio Memorial Committee) feel the Lord lead us to establish<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[6024,3525,1038,327,7422,782,1033,7330],"class_list":["post-18094","post","type-post","status-publish","format-standard","hentry","category-churches","tag-american-flag","tag-committee","tag-freedom","tag-memorial","tag-north-scipio-veteran-memorial","tag-pray","tag-veterans","tag-worship"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"News Submissions\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"West Bend News | Northwest Ohio and Northeast Indiana Local News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"North Scipio Veteran Memorial | West Bend News\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-01T11:30:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-27T13:04:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"North Scipio Veteran Memorial | West Bend News\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&amp;ssl=1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#article\",\"name\":\"North Scipio Veteran Memorial | West Bend News\",\"headline\":\"North Scipio Veteran Memorial\",\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/North-Scipio-Veterans-Memorial-2.jpg\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#articleImage\"},\"datePublished\":\"2017-07-01T07:30:27-04:00\",\"dateModified\":\"2017-06-27T09:04:42-04:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#webpage\"},\"articleSection\":\"Churches, American Flag, committee, freedom, memorial, North Scipio Veteran Memorial, Pray, veterans, Worship\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/churches\\\/#listItem\",\"name\":\"Churches\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/churches\\\/#listItem\",\"position\":2,\"name\":\"Churches\",\"item\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/churches\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#listItem\",\"name\":\"North Scipio Veteran Memorial\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#listItem\",\"position\":3,\"name\":\"North Scipio Veteran Memorial\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/category\\\/churches\\\/#listItem\",\"name\":\"Churches\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\",\"name\":\"West Bend News and Printing\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"telephone\":\"+14192582000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.westbendnews.net\\\/autonews\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png?fit=1067%2C206&ssl=1\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#organizationLogo\",\"width\":1067,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/\",\"name\":\"News Submissions\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"News Submissions\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#webpage\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/\",\"name\":\"North Scipio Veteran Memorial | West Bend News\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/north-scipio-veteran-memorial\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/author\\\/newssubs\\\/#author\"},\"datePublished\":\"2017-07-01T07:30:27-04:00\",\"dateModified\":\"2017-06-27T09:04:42-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#website\",\"url\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/\",\"name\":\"West Bend News\",\"description\":\"Northwest Ohio and Northeast Indiana Local News\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westbendnews.net\\\/autonews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"North Scipio Veteran Memorial | West Bend News","description":"","canonical_url":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#article","name":"North Scipio Veteran Memorial | West Bend News","headline":"North Scipio Veteran Memorial","author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2017\/06\/North-Scipio-Veterans-Memorial-2.jpg","@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#articleImage"},"datePublished":"2017-07-01T07:30:27-04:00","dateModified":"2017-06-27T09:04:42-04:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#webpage"},"isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#webpage"},"articleSection":"Churches, American Flag, committee, freedom, memorial, North Scipio Veteran Memorial, Pray, veterans, Worship"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","position":1,"name":"Home","item":"https:\/\/www.westbendnews.net\/autonews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/churches\/#listItem","name":"Churches"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/churches\/#listItem","position":2,"name":"Churches","item":"https:\/\/www.westbendnews.net\/autonews\/category\/churches\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#listItem","name":"North Scipio Veteran Memorial"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#listItem","position":3,"name":"North Scipio Veteran Memorial","previousItem":{"@type":"ListItem","@id":"https:\/\/www.westbendnews.net\/autonews\/category\/churches\/#listItem","name":"Churches"}}]},{"@type":"Organization","@id":"https:\/\/www.westbendnews.net\/autonews\/#organization","name":"West Bend News and Printing","description":"Northwest Ohio and Northeast Indiana Local News","url":"https:\/\/www.westbendnews.net\/autonews\/","telephone":"+14192582000","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Logo.png?fit=1067%2C206&ssl=1","@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#organizationLogo","width":1067,"height":206},"image":{"@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author","url":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/","name":"News Submissions","image":{"@type":"ImageObject","@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c80655cd4f51e6939a501dbfe5ec59d8b7ac0e8978b70b0ae2cc2718917a12aa?s=96&d=mm&r=pg","width":96,"height":96,"caption":"News Submissions"}},{"@type":"WebPage","@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#webpage","url":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/","name":"North Scipio Veteran Memorial | West Bend News","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#website"},"breadcrumb":{"@id":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/#breadcrumblist"},"author":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"creator":{"@id":"https:\/\/www.westbendnews.net\/autonews\/author\/newssubs\/#author"},"datePublished":"2017-07-01T07:30:27-04:00","dateModified":"2017-06-27T09:04:42-04:00"},{"@type":"WebSite","@id":"https:\/\/www.westbendnews.net\/autonews\/#website","url":"https:\/\/www.westbendnews.net\/autonews\/","name":"West Bend News","description":"Northwest Ohio and Northeast Indiana Local News","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.westbendnews.net\/autonews\/#organization"}}]},"og:locale":"en_US","og:site_name":"West Bend News | Northwest Ohio and Northeast Indiana Local News","og:type":"article","og:title":"North Scipio Veteran Memorial | West Bend News","og:url":"https:\/\/www.westbendnews.net\/autonews\/north-scipio-veteran-memorial\/","og:image":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1","og:image:secure_url":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&#038;ssl=1","article:published_time":"2017-07-01T11:30:27+00:00","article:modified_time":"2017-06-27T13:04:42+00:00","twitter:card":"summary","twitter:title":"North Scipio Veteran Memorial | West Bend News","twitter:image":"https:\/\/i0.wp.com\/www.westbendnews.net\/autonews\/wp-content\/uploads\/2022\/01\/Front-Page-Header.jpg?fit=1200%2C300&ssl=1"},"aioseo_meta_data":{"post_id":"18094","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-06 20:38:41","updated":"2025-06-04 23:44:17","seo_analyzer_scan_date":null},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2YQd9-4HQ","jetpack-related-posts":[],"jetpack_likes_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:35:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/18094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/comments?post=18094"}],"version-history":[{"count":0,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/posts\/18094\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/media?parent=18094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/categories?post=18094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westbendnews.net\/autonews\/wp-json\/wp\/v2\/tags?post=18094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}